{"id":3247,"date":"2021-05-29T22:31:16","date_gmt":"2021-05-30T03:31:16","guid":{"rendered":"http:\/\/transitobucaramanga.gov.co\/dtb\/?page_id=3247"},"modified":"2026-04-06T09:01:56","modified_gmt":"2026-04-06T14:01:56","slug":"accidentalidad","status":"publish","type":"page","link":"https:\/\/transitobucaramanga.gov.co\/dtb\/atencion-y-servicios-a-la-ciudadania\/movilidad\/accidentalidad","title":{"rendered":"Accidentalidad"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><nav class=\"fusion-breadcrumbs fusion-breadcrumbs-1\" style=\"--awb-breadcrumb-sep:&#039;\/&#039;;\" aria-label=\"Breadcrumb\"><ol class=\"awb-breadcrumb-list\"><li class=\"fusion-breadcrumb-item awb-breadcrumb-sep awb-home\" ><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\" class=\"fusion-breadcrumb-link\"><span >Home<\/span><\/a><\/li><\/ol><\/nav><div class=\"fusion-title title fusion-title-1 fusion-title-center fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><div class=\"title-sep-container title-sep-container-left\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer\"><\/span><h1 class=\"fusion-title-heading title-heading-center\" style=\"margin:0;\">Accidentalidad<\/h1><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-shadow\" style=\"--awb-height:20px;--awb-amount:20px;background:radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-webkit-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-moz-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-o-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);\"><\/div><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div align=\"center\" >\n<iframe class=\"lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271280%27%20height%3D%271024%27%20viewBox%3D%270%200%201280%201024%27%3E%3Crect%20width%3D%271280%27%20height%3D%271024%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/srvansvargweb.ansv.gov.co\/portalansv\/apps\/dashboards\/4e64c90f66174d3d8ce710f578f99617\" width=\"1280\" height=\"1024\"><\/iframe><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div align=\"center\" >\n<iframe class=\"lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27640%27%20height%3D%27480%27%20viewBox%3D%270%200%20640%20480%27%3E%3Crect%20width%3D%27640%27%20height%3D%27480%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.google.com\/maps\/d\/u\/0\/embed?mid=1mL09aXPI8-PJFWWRRnvbJJ9O-yO19jyQ\" width=\"640\" height=\"480\"><\/iframe><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-title-center fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><div class=\"title-sep-container title-sep-container-left\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer\"><\/span><h2 class=\"fusion-title-heading title-heading-center\" style=\"margin:0;\">Informe de <span style=\"color: #32ba3d;\">Gesti\u00f3n<\/span> Grupo de Control Vial<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:13px;--awb-content-font-size:14px;--awb-icon-alignment:left;--awb-hover-color:#f9f9f9;--awb-border-color:#cccccc;--awb-background-color:#ffffff;--awb-divider-color:#e0dede;--awb-divider-hover-color:#e0dede;--awb-icon-color:#ffffff;--awb-title-color:#333333;--awb-content-color:#747474;--awb-icon-box-color:#333333;--awb-toggle-hover-accent-color:#32ba3d;--awb-title-font-family:&quot;Barlow&quot;;--awb-title-font-weight:700;--awb-title-font-style:normal;--awb-title-font-size:14px;--awb-content-font-family:&quot;Barlow&quot;;--awb-content-font-style:normal;--awb-content-font-weight:500;\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-3247-1\"><div class=\"fusion-panel panel-default panel-6abd0f4613af0a71a fusion-toggle-has-divider\" style=\"--awb-title-color:#333333;--awb-content-color:#747474;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_6abd0f4613af0a71a\"><a aria-expanded=\"false\" aria-controls=\"6abd0f4613af0a71a\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#6abd0f4613af0a71a\" href=\"#6abd0f4613af0a71a\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2026<\/span><\/a><\/h4><\/div><div id=\"6abd0f4613af0a71a\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_6abd0f4613af0a71a\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2026\/04\/INFORME-GESTION-GRUPO-CONTROL-VIAL-SINIESTROS-VIALES-ENE-MARZO-2026.pdf\" target=\"_blank\" rel=\"noopener\">Informe de Gesti\u00f3n &#8211; Control Vial &#8211; Accidentalidad &#8211; enero a marzo 2026<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-cbd35d71dc6bc7719 fusion-toggle-has-divider\" style=\"--awb-title-color:#333333;--awb-content-color:#747474;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_cbd35d71dc6bc7719\"><a aria-expanded=\"false\" aria-controls=\"cbd35d71dc6bc7719\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#cbd35d71dc6bc7719\" href=\"#cbd35d71dc6bc7719\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2025<\/span><\/a><\/h4><\/div><div id=\"cbd35d71dc6bc7719\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_cbd35d71dc6bc7719\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2025\/04\/INFORME-GESTION-GRUPO-CONTROL-VIAL-2025-ENERO-MARZO-ACCIDENTALIDAD.pdf\" target=\"_blank\" rel=\"noopener\">Informe de Gesti\u00f3n &#8211; Control Vial &#8211; Accidentalidad &#8211; enero a marzo 2025<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2025\/07\/INFORME-GESTION-GRUPO-CONTROL-VIAL-2025-ENERO-JUNIO-ACCIDENTALIDAD.pdf\" target=\"_blank\" rel=\"noopener\">Informe de Gesti\u00f3n &#8211; Control Vial &#8211; Accidentalidad &#8211; enero a junio 2025<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2025\/10\/INFORME-GESTION-GRUPO-CONTROL-VIAL-2025-ENERO-SEPTIEMBRE-ACCIDENTALIDAD.pdf\" target=\"_blank\" rel=\"noopener\">Informe de Gesti\u00f3n &#8211; Control Vial &#8211; Accidentalidad &#8211; enero a septiembre 2025<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2026\/01\/INFORME-GESTION-GRUPO-CONTROL-VIAL-SINIESTROS-2025-ENERO-DIC.pdf\" target=\"_blank\" rel=\"noopener\">Informe de Gesti\u00f3n &#8211; Control Vial &#8211; Accidentalidad &#8211; enero a diciembre 2025<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-b9f4a0b965c571859 fusion-toggle-has-divider\" style=\"--awb-title-color:#333333;--awb-content-color:#747474;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_b9f4a0b965c571859\"><a aria-expanded=\"false\" aria-controls=\"b9f4a0b965c571859\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#b9f4a0b965c571859\" href=\"#b9f4a0b965c571859\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2024<\/span><\/a><\/h4><\/div><div id=\"b9f4a0b965c571859\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_b9f4a0b965c571859\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2024\/04\/INFORME-GESTION-GRUPO-CONTROL-VIAL-2024-ENE-MAR-ACCIDENTES.pdf\" target=\"_blank\" rel=\"noopener\">Incidentes Viales enero a marzo<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2024\/07\/INFORME-GESTION-GRUPO-CONTROL-VIAL-2024-ENERO-JUNIO-ACCIDENTES.pdf\" target=\"_blank\" rel=\"noopener\">Incidentes Viales enero a junio<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2024\/10\/161024-INFORME-GESTION-GRUPO-CONTROL-VIAL-2024-ENERO-SEPTIEMBRE-ACCIDENTALIDAD.pdf\" target=\"_blank\" rel=\"noopener\">Incidentes Viales enero a septiembre<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2025\/01\/INFORME-GESTION-GRUPO-CONTROL-VIAL-2024-ENERO-DICIEMBRE-SINIESTROS-VIALES.pdf\" target=\"_blank\" rel=\"noopener\">Incidentes Viales enero a diciembre<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-a997ac0a27c0a1804 fusion-toggle-has-divider\" style=\"--awb-title-color:#333333;--awb-content-color:#747474;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_a997ac0a27c0a1804\"><a aria-expanded=\"false\" aria-controls=\"a997ac0a27c0a1804\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#a997ac0a27c0a1804\" href=\"#a997ac0a27c0a1804\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2023<\/span><\/a><\/h4><\/div><div id=\"a997ac0a27c0a1804\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_a997ac0a27c0a1804\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2023\/04\/INCIDENTES-VIALES-ANO-2023-ENERO-MARZO.pdf\" target=\"_blank\" rel=\"noopener\">Incidentes Viales enero a marzo<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2023\/07\/INFORME-GESTION-GRUPO-CONTROL-VIAL-2023-ENERO-A-JUNIO-ACCIDENTALIDAD.pdf\" target=\"_blank\" rel=\"noopener\">Incidentes Viales enero a junio<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2023\/10\/INFORME-GESTION-GRUPO-CONTROL-VIAL-2023-ENERO-A-SEPTIEMBRE-ACCIDENTALIDAD.pdf\" target=\"_blank\" rel=\"noopener\">Incidentes Viales enero a septiembre<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2024\/01\/INFORME-ACCIDENTALIDAD-VIAL-ANO-2023.pdf\" target=\"_blank\" rel=\"noopener\">Informe de Gesti\u00f3n Accidentalidad enero a diciembre<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-653b53937b9edac6f fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_653b53937b9edac6f\"><a aria-expanded=\"false\" aria-controls=\"653b53937b9edac6f\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#653b53937b9edac6f\" href=\"#653b53937b9edac6f\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2022<\/span><\/a><\/h4><\/div><div id=\"653b53937b9edac6f\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_653b53937b9edac6f\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2022\/04\/190422-Informe-de-Gestion-Control-Vial-Enero-a-Marzo-2022-accidentalidad-v2.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a marzo<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2022\/07\/080722-Informe-de-Gestion-Control-Vial-Enero-a-Junio-2022-accidentalidad.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a junio<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2022\/10\/051022-Informe-de-Gestion-Control-Vial-Enero-a-Septiembre-2022-accidentalidad.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a septiembre<\/a><\/p>\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2023\/01\/INFORME-ACCIDENTALIDAD-GESTION-GRUPO-CONTROL-VIAL-2022.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a diciembre<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-4bfbdde00283ce4a3 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_4bfbdde00283ce4a3\"><a aria-expanded=\"false\" aria-controls=\"4bfbdde00283ce4a3\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#4bfbdde00283ce4a3\" href=\"#4bfbdde00283ce4a3\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2021<\/span><\/a><\/h4><\/div><div id=\"4bfbdde00283ce4a3\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_4bfbdde00283ce4a3\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/05\/Accidentalidad-enero-a-marzo-2021.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a marzo<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/07\/INFORME-GESTION-GRUPO-CONTROL-VIAL-ENERO-A-JUNIO-2021-ACCIDENTALIDAD.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a junio<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/10\/INFORME-GESTION-GRUPO-CONTROL-VIAL-ENERO-ACCIDENTALIDAD-A-SEPTIEMBRE-2021.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a septiembre<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2022\/02\/230222-Informe-de-Gestion-Control-Vial-Enero-a-Diciembre-2022-Accidentalidad-v3.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a diciembre<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-2cd33c1383c8b33c5 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_2cd33c1383c8b33c5\"><a aria-expanded=\"false\" aria-controls=\"2cd33c1383c8b33c5\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#2cd33c1383c8b33c5\" href=\"#2cd33c1383c8b33c5\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2020<\/span><\/a><\/h4><\/div><div id=\"2cd33c1383c8b33c5\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_2cd33c1383c8b33c5\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/200420-inf-gest-enero-marzo-accidentalidad.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a marzo<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/100720-accidentalidad-inf-gest-control-vial.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a junio<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/141020-accidentalidad-inf-gest-control-vial.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a septiembre<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/080121-accidentalidad-inf-gestion-ene-dic-2020.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a diciembre<\/a><\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-423ae61141cb47001 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_423ae61141cb47001\"><a aria-expanded=\"false\" aria-controls=\"423ae61141cb47001\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#423ae61141cb47001\" href=\"#423ae61141cb47001\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2019<\/span><\/a><\/h4><\/div><div id=\"423ae61141cb47001\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_423ae61141cb47001\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentes-ene-mar-2019.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a marzo<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-enero-junio-2019.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a junio<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentes-ene-ago-2019.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a agosto<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/230120-accidentalidad-inf-gest-control-vial.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a diciembre<\/a><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-f8943b289cdc1e541 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f8943b289cdc1e541\"><a aria-expanded=\"false\" aria-controls=\"f8943b289cdc1e541\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#f8943b289cdc1e541\" href=\"#f8943b289cdc1e541\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2018<\/span><\/a><\/h4><\/div><div id=\"f8943b289cdc1e541\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_f8943b289cdc1e541\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-corte-310118.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentes-corte-280218.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a febrero<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-ene-feb-mar-2018-250418.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a marzo<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-ene-jun-2018-090718.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a junio<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/relacion-accidentes-ene-sep-2018-111018.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a septiembre<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-diciembre-2018-2.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a diciembre<\/a><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-7d27ee15cc210d89d fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_7d27ee15cc210d89d\"><a aria-expanded=\"false\" aria-controls=\"7d27ee15cc210d89d\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#7d27ee15cc210d89d\" href=\"#7d27ee15cc210d89d\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2017<\/span><\/a><\/h4><\/div><div id=\"7d27ee15cc210d89d\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_7d27ee15cc210d89d\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-corte-310317.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; marzo<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-corte-150517.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; mayo<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-corte-310517.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a mayo<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-I-semestre-2017-270717.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a junio<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-corte-051017.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a septiembre<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-corte-301117.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a noviembre<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-corte-311217.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a diciembre<\/a><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-2ac37f2226a953fdb fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_2ac37f2226a953fdb\"><a aria-expanded=\"false\" aria-controls=\"2ac37f2226a953fdb\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#2ac37f2226a953fdb\" href=\"#2ac37f2226a953fdb\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2016<\/span><\/a><\/h4><\/div><div id=\"2ac37f2226a953fdb\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_2ac37f2226a953fdb\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/controlVial-primerSemestre-2016.pdf\" target=\"_blank\" rel=\"noopener\">Informe Gesti\u00f3n &#8211; enero a junio<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/Accidentalidad-primersemestre-2016.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a junio<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-7julio2016.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; julio 07<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-050916.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; septiembre 05<\/a><br \/>\n<a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/accidentalidad-corte-311216.pdf\" target=\"_blank\" rel=\"noopener\">Accidentalidad &#8211; enero a diciembre<\/a><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-742c959e2799de339 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_742c959e2799de339\"><a aria-expanded=\"false\" aria-controls=\"742c959e2799de339\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#742c959e2799de339\" href=\"#742c959e2799de339\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2015<\/span><\/a><\/h4><\/div><div id=\"742c959e2799de339\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_742c959e2799de339\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/InformeGestion2015.pdf\" target=\"_blank\" rel=\"noopener\">Informe Gesti\u00f3n<\/a><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-db5b03e4157e1f689 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_db5b03e4157e1f689\"><a aria-expanded=\"false\" aria-controls=\"db5b03e4157e1f689\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#db5b03e4157e1f689\" href=\"#db5b03e4157e1f689\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2013<\/span><\/a><\/h4><\/div><div id=\"db5b03e4157e1f689\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_db5b03e4157e1f689\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/Comparativo-accidentalidad-2012-2013.pdf\" target=\"_blank\" rel=\"noopener\">Informe Gesti\u00f3n<\/a><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-530bb30b3d1269926 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_530bb30b3d1269926\"><a aria-expanded=\"false\" aria-controls=\"530bb30b3d1269926\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#530bb30b3d1269926\" href=\"#530bb30b3d1269926\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2012<\/span><\/a><\/h4><\/div><div id=\"530bb30b3d1269926\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_530bb30b3d1269926\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/Comparativo-accidentalidad-2011-2012.pdf\" target=\"_blank\" rel=\"noopener\">Informe Gesti\u00f3n<\/a><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-41efed35d4a878cde fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_41efed35d4a878cde\"><a aria-expanded=\"false\" aria-controls=\"41efed35d4a878cde\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#41efed35d4a878cde\" href=\"#41efed35d4a878cde\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2011<\/span><\/a><\/h4><\/div><div id=\"41efed35d4a878cde\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_41efed35d4a878cde\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/Comparativo-accidentalidad-2010-2011.pdf\" target=\"_blank\" rel=\"noopener\">Informe Gesti\u00f3n<\/a><\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-0a5b659c834f1365c fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_0a5b659c834f1365c\"><a aria-expanded=\"false\" aria-controls=\"0a5b659c834f1365c\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-3247-1\" data-target=\"#0a5b659c834f1365c\" href=\"#0a5b659c834f1365c\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">2010<\/span><\/a><\/h4><\/div><div id=\"0a5b659c834f1365c\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_0a5b659c834f1365c\"><div class=\"panel-body toggle-content fusion-clearfix\"><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-content\/uploads\/2021\/09\/Comparativo-accidentalidad-2009-2010.pdf\" target=\"_blank\" rel=\"noopener\">Informe Gesti\u00f3n<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2306,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3247","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages\/3247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/comments?post=3247"}],"version-history":[{"count":44,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages\/3247\/revisions"}],"predecessor-version":[{"id":12199,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages\/3247\/revisions\/12199"}],"up":[{"embeddable":true,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages\/2306"}],"wp:attachment":[{"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/media?parent=3247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}