{"id":9055,"date":"2024-02-21T12:00:13","date_gmt":"2024-02-21T17:00:13","guid":{"rendered":"https:\/\/transitobucaramanga.gov.co\/dtb\/?page_id=9055"},"modified":"2024-02-21T14:37:51","modified_gmt":"2024-02-21T19:37:51","slug":"ejecucion-presupuestal-presupuesto-y-estados-financieros","status":"publish","type":"page","link":"https:\/\/transitobucaramanga.gov.co\/dtb\/transparencia\/planeacion-presupuesto-e-informes\/ejecucion-presupuestal-presupuesto-y-estados-financieros","title":{"rendered":"Ejecuci\u00f3n Presupuestal, Presupuesto y Estados Financieros"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><nav class=\"fusion-breadcrumbs fusion-breadcrumbs-1\" style=\"--awb-breadcrumb-sep:&#039;\/&#039;;\" aria-label=\"Breadcrumb\"><ol class=\"awb-breadcrumb-list\"><li class=\"fusion-breadcrumb-item awb-breadcrumb-sep awb-home\" ><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\" class=\"fusion-breadcrumb-link\"><span >Home<\/span><\/a><\/li><\/ol><\/nav><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-title-center fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><div class=\"title-sep-container title-sep-container-left\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer\"><\/span><h1 class=\"fusion-title-heading title-heading-center\" style=\"margin:0;\">Ejecuci\u00f3n Presupuestal, Presupuesto y Estados Financieros<\/h1><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-shadow\" style=\"--awb-height:20px;--awb-amount:20px;background:radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-webkit-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-moz-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-o-radial-gradient(ellipse at 50% -50% , #e0dede 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-3 fusion-columns-total-3 fusion-content-boxes-1 content-boxes-clean-horizontal content-left content-boxes-icon-on-side fusion-delayed-animation\" style=\"--awb-backgroundcolor:#f4f2f2;--awb-body-color:#212326;--awb-title-color:#141617;--awb-iconcolor:#ffffff;--awb-margin-bottom:0px;--awb-hover-accent-color:#141617;--awb-circle-hover-accent-color:#141617;\" data-animation-delay=\"500\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:#f4f2f2;--awb-iconcolor:#ffffff;--awb-content-padding-left:68px;border-color:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-4 col-md-4 col-sm-4 fusion-content-box-hover content-box-column-first-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-link-icon link-type-text icon-hover-animation-slide fusion-animated\" data-animationType=\"fadeInLeft\" data-animationDuration=\"2.0\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"#\" target=\"_self\"><div class=\"icon\" style=\"-webkit-animation-duration: 500ms;animation-duration: 500ms;\"><i style=\"border-color:#333333;border-width:0px;background-color:#007c89;box-sizing:content-box;height:48px;width:48px;line-height:48px;border-radius:8px;font-size:24px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-file-invoice-dollar fas circle-yes\"><\/i><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:24px;--fontSize:24;line-height:1.67;padding-left:68px;\">Presupuesto General<\/h3><\/a><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<h3><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/transparencia\/planeacion-presupuesto-e-informes\/ejecucion-presupuestal-presupuesto-y-estados-financieros\/presupuesto-general-dtb\">Consultar<\/a><\/h3>\n<\/div><\/div><\/div><div style=\"--awb-backgroundcolor:#f4f2f2;--awb-iconcolor:#ffffff;--awb-content-padding-left:68px;border-color:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-2 col-lg-4 col-md-4 col-sm-4 fusion-content-box-hover \"><div class=\"col content-box-wrapper content-wrapper-background link-area-link-icon link-type-text icon-hover-animation-slide fusion-animated\" data-animationType=\"fadeInLeft\" data-animationDuration=\"2.0\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"#\" target=\"_self\"><div class=\"icon\" style=\"-webkit-animation-duration: 500ms;animation-duration: 500ms;\"><i style=\"border-color:#333333;border-width:0px;background-color:#007c89;box-sizing:content-box;height:48px;width:48px;line-height:48px;border-radius:8px;font-size:24px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-file-invoice-dollar fas circle-yes\"><\/i><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:24px;--fontSize:24;line-height:1.67;padding-left:68px;\">Ejecuci\u00f3n Presupuestal Hist\u00f3rica Anual<\/h3><\/a><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<h3><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/transparencia\/planeacion-presupuesto-e-informes\/ejecucion-presupuestal-presupuesto-y-estados-financieros\/ejecucion-presupuestal-historica-anual\">Consultar<\/a><\/h3>\n<\/div><\/div><\/div><div style=\"--awb-backgroundcolor:#f4f2f2;--awb-iconcolor:#ffffff;--awb-content-padding-left:68px;border-color:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-3 col-lg-4 col-md-4 col-sm-4 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper-background link-area-link-icon link-type-text icon-hover-animation-slide fusion-animated\" data-animationType=\"fadeInLeft\" data-animationDuration=\"2.0\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><a class=\"heading-link\" href=\"#\" target=\"_self\"><div class=\"icon\" style=\"-webkit-animation-duration: 500ms;animation-duration: 500ms;\"><i style=\"border-color:#333333;border-width:0px;background-color:#007c89;box-sizing:content-box;height:48px;width:48px;line-height:48px;border-radius:8px;font-size:24px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-file-invoice-dollar fas circle-yes\"><\/i><\/div><h3 class=\"content-box-heading fusion-responsive-typography-calculated\" style=\"--h3_typography-font-size:24px;--fontSize:24;line-height:1.67;padding-left:68px;\">Estados Financieros<\/h3><\/a><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<h3><a href=\"https:\/\/transitobucaramanga.gov.co\/dtb\/transparencia\/planeacion-presupuesto-e-informes\/ejecucion-presupuestal-presupuesto-y-estados-financieros\/estados-financieros\">Consultar<\/a><\/h3>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":3054,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9055","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages\/9055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/comments?post=9055"}],"version-history":[{"count":3,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages\/9055\/revisions"}],"predecessor-version":[{"id":9105,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages\/9055\/revisions\/9105"}],"up":[{"embeddable":true,"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/pages\/3054"}],"wp:attachment":[{"href":"https:\/\/transitobucaramanga.gov.co\/dtb\/wp-json\/wp\/v2\/media?parent=9055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}